{"id":1019,"date":"2019-04-17T12:00:00","date_gmt":"2019-04-17T12:00:00","guid":{"rendered":"http:\/\/wec-new-site.local\/entrevista-solar-tracker-set100\/"},"modified":"2019-04-17T12:00:00","modified_gmt":"2019-04-17T12:00:00","slug":"entrevista-solar-tracker-set100","status":"publish","type":"post","link":"https:\/\/wec-chile.cl\/en\/entrevista-solar-tracker-set100\/","title":{"rendered":"Entrevista Solar Tracker SET100"},"content":{"rendered":"<p>El ingeniero civil de 28 a\u00f1os es uno de los dos seleccionados a nivel global para presentar su proyecto Solar Tracker en el concurso SET100, organizado por WEC, el cual busca premiar los proyectos m\u00e1s innovadores que hagan frente a la actual transici\u00f3n energ\u00e9tica.<\/p>\n<p>1. \u00bfDe qu\u00e9 se trata tu proyecto?<br \/>\nLa visi\u00f3n de SolarTracker es potenciar el desarrollo de la energ\u00eda solar distribuida, a trav\u00e9s de la democratizaci\u00f3n de la inteligencia en la operaci\u00f3n de las plantas fotovoltaicas. Lo que buscamos es que las plantas aumenten la producci\u00f3n durante toda su vida \u00fatil, y as\u00ed optimizar la operaci\u00f3n y mantenimiento. De esta forma, aumentamos la rentabilidad de los proyectos y ayudamos\u00a0 a que la energ\u00eda solar llegue a m\u00e1s partes del mundo. Para esto, creamos un servicio de monitoreo inteligente. Lo que hacemos, es obtener los datos de operaci\u00f3n de las plantas solares, y las condiciones ambientales mediante datos satelitales. Luego, utilizando Inteligencia Artificial (IA), analizamos el rendimiento de cada una de las plantas, para detectar y diagnosticar en forma autom\u00e1tica cualquier problema en la operaci\u00f3n. A partir de esto, generamos reportes, alertas y planificaciones de mantenimiento para que los operadores puedan tomar decisiones con informaci\u00f3n clara y precisa. Por otro lado, los inversionistas, o due\u00f1os de las plantas, obtienen informaci\u00f3n transparente del rendimiento de su sistema, y de las labores del operador.<\/p>\n<p>2. \u00bfC\u00f3mo se te ocurri\u00f3 postular y qu\u00e9 sentiste al ser clasificado?<br \/>\nNos hab\u00edamos enterados del concurso el 2017, y postulamos en enero del 2018 por primera vez. Entonces, solo ten\u00edamos una idea de lo que quer\u00edamos hacer. A fines del 2018, nos lleg\u00f3 un correo invit\u00e1ndonos nuevamente a postular. No lo pensamos dos veces, y empezamos a prepararnos. Adem\u00e1s, la empresa ya estaba en una etapa m\u00e1s avanzada, y nuestra tecnolog\u00eda y modelo de negocio estaban m\u00e1s maduros.\u00a0 Cuando nos avisaron que hab\u00edamos sido seleccionados, no ten\u00eda muy clara la dimensi\u00f3n de la noticia. Lo coment\u00e9 con el equipo, y fue entonces que sent\u00ed la adrenalina. Est\u00e1bamos todos muy felices, porque era el primer reconocimiento internacional que recib\u00edamos y m\u00e1s encima en un evento de nivel global.<\/p>\n<p>3. \u00bfHab\u00edas formado parte de alg\u00fan concurso de este tipo antes? \u00bfQu\u00e9 sientes?<br \/>\nHemos postulado y participado de muchos fondos y eventos, pero a ninguno de esta envergadura. Me parece muy excitante ser parte de un congreso donde estar\u00e1n presentes StartUps de todo el mundo que trabajan enfocados en revertir el cambio clim\u00e1tico. Creo que poder compartir con pares de todas partes, ser\u00e1 una experiencia incre\u00edble. Mi expectativa, es poder conocer personas de todos lados, que puedan ser amigos, partners o clientes, para poder conectarnos y compartir informaci\u00f3n, experiencias y redes sobre emprendiendo, empresas verdes, etc.<\/p>\n<p>4. \u00bfCu\u00e1les son tus expectativas? \u00bfQu\u00e9 piensas hacer a futuro con este proyecto?Con SolarTracker queremos seguir potenciando el desarrollo de la energ\u00eda solar en todo el mundo<\/p>","protected":false},"excerpt":{"rendered":"<p>El ingeniero civil de 28 a\u00f1os es uno de los dos seleccionados a nivel global para presentar su proyecto Solar Tracker en el concurso SET100, organizado por WEC, el cual busca premiar los proyectos&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1019","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts\/1019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/comments?post=1019"}],"version-history":[{"count":0,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts\/1019\/revisions"}],"wp:attachment":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/media?parent=1019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/categories?post=1019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/tags?post=1019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}