{"id":1055,"date":"2019-02-07T12:00:00","date_gmt":"2019-02-07T12:00:00","guid":{"rendered":"http:\/\/wec-new-site.local\/proyecto-del-ministerio-de-energ-a-gana-concurso-del-bid\/"},"modified":"2019-02-07T12:00:00","modified_gmt":"2019-02-07T12:00:00","slug":"proyecto-del-ministerio-de-energ-a-gana-concurso-del-bid","status":"publish","type":"post","link":"https:\/\/wec-chile.cl\/en\/proyecto-del-ministerio-de-energ-a-gana-concurso-del-bid\/","title":{"rendered":"Proyecto del Ministerio de Energ\u00eda gana concurso del BID"},"content":{"rendered":"<p>La iniciativa de g\u00e9nero del Ministerio de energ\u00eda obtuvo el primer lugar en el concurso organizado por la divisi\u00f3n de energ\u00eda del Banco Interamericano de Desarrollo v\u00e1lida para latinoamerica y el caribe.<\/p>\n<p>La propuesta ganadora de Paulina Guiti\u00e9rrez y Marcela Zulantay\u00a0consiste en\u00a0un Plan de Acci\u00f3n P\u00fablico-Privado para promover la inserci\u00f3n progresiva de la mujer en la industria energ\u00e9tica nacional. De esto la comisi\u00f3n evaluadora del BID destac\u00f3\u00a0la conformaci\u00f3n y puesta en marcha de la\u00a0Mesa de Trabajo P\u00fablico-Privada de Energ\u00eda y G\u00e9nero, de la cual forma parte Javiera Aldunate.<\/p>\n<p>Desde el ministerio,\u00a0Paula Est\u00e9vez, jefa Unidad Relaciones Internacionales expuso a la revista ELECTRICIDAD que \u201clos esfuerzos de los actores p\u00fablicos y privados del sector energ\u00e9tico estuvieron puestos en realizar un Diagn\u00f3stico sobre las barreras y los desaf\u00edos que las mujeres tienen en esta industria, a trav\u00e9s de un proceso participativo que se extendi\u00f3 de agosto de 2018 a enero de 2019.\u201d<\/p>\n<p>En tanto, el reconocimiento del Banco Interamericano de Desarrollo al sector y a esta iniciativa p\u00fablico-privada se materializar\u00e1 en Washington durante 2019.<\/p>\n<p>Fuente: Revista Electricidad<\/p>","protected":false},"excerpt":{"rendered":"<p>La iniciativa de g\u00e9nero del Ministerio de energ\u00eda obtuvo el primer lugar en el concurso organizado por la divisi\u00f3n de energ\u00eda del Banco Interamericano de Desarrollo v\u00e1lida para latinoamerica y el&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1055","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts\/1055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/comments?post=1055"}],"version-history":[{"count":0,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts\/1055\/revisions"}],"wp:attachment":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/media?parent=1055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/categories?post=1055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/tags?post=1055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}