{"id":1100,"date":"2018-10-09T12:00:00","date_gmt":"2018-10-09T12:00:00","guid":{"rendered":"http:\/\/wec-new-site.local\/wew-d-a-2-conocemos-el-energy-toolkit\/"},"modified":"2018-10-09T12:00:00","modified_gmt":"2018-10-09T12:00:00","slug":"wew-d-a-2-conocemos-el-energy-toolkit","status":"publish","type":"post","link":"https:\/\/wec-chile.cl\/en\/wew-d-a-2-conocemos-el-energy-toolkit\/","title":{"rendered":"WEW d\u00eda 2: conocemos el Energy Toolkit"},"content":{"rendered":"<p>Transformar reportes en herramientas: la clave para una transici\u00f3n energ\u00e9tica positiva, coordinada y sustentable.<\/p>\n<p>En la segunda jornada de la World Energy Week, el evento anual organizado por World Energy Council que se lleva a cabo en Mil\u00e1n, Italia, se present\u00f3 el Toolkit: un conjunto de recursos, sugerencias y planes de acci\u00f3n desarrollado por miembros del Consejo con el objetivo de facilitar una transici\u00f3n energ\u00e9tica exitosa.<\/p>\n<p>El equipo de WEC Chile estuvo presente en la ma\u00f1ana de Revisi\u00f3n Estrat\u00e9gica de los miembros, en la que se dio a conocer el Toolkit, que busca transformar los reportes y an\u00e1lisis de la industria energ\u00e9tica global por herramientas concretas para promover la conversaci\u00f3n estrat\u00e9gica y la cooperaci\u00f3n entre los l\u00edderes, futuros l\u00edderes y expertos de la energ\u00eda de todos los \u00e1mbitos de la cadena de valor.<\/p>\n<p>&quot;Las formas en las que las personas alrededor del mundo producen, consumen y comercializan la energ\u00eda est\u00e1 cambiando. Nuevos roles est\u00e1n emergiendo -por ejemplo, los llamados &#x27;prosumidores&#x27; de energ\u00eda. Los l\u00edmites entre sectores se vuelven difusos. Los servicios de energ\u00eda prosperan. El crecimiento en la diversidad de recursos energ\u00e9ticos se refleja en el crecimiento en la complejidad social de los nuevos actores dentro del sistema. El alza en el poder de nuevas personas es evidente: ciudades globalmente conectadas, comunidades rurales con acceso a energ\u00edas renovables y consumidores empoderados digitalmente ya est\u00e1n demandando nuevos servicios de energ\u00eda&quot;.<\/p>\n<p>Con esta introducci\u00f3n, Christoph Frei y Angela Wilkinson hacen la introducci\u00f3n a un panorama energ\u00e9tico mundial que requiere del uso coordinado y eficiente de este Toolkit para la Transici\u00f3n Energ\u00e9tica.<\/p>\n<p>Durante la tarde, se realiz\u00f3 la Asamblea Ejecutiva donde se presentaron los pr\u00f3ximos encuentros que se realizar\u00e1n: el 24to. Congreso anual de la Energ\u00eda 2019, en Abu Dhabi; la Semana de la Energ\u00eda 2020, en Beirut, L\u00edbano; y el Congreso Anual de la Energ\u00eda 2022 en San Petersburgo, Rusia.<\/p>","protected":false},"excerpt":{"rendered":"<p>Transformar reportes en herramientas: la clave para una transici\u00f3n energ\u00e9tica positiva, coordinada y sustentable. En la segunda jornada de la World Energy Week, el evento anual organizado por World&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1100","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts\/1100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/comments?post=1100"}],"version-history":[{"count":0,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts\/1100\/revisions"}],"wp:attachment":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/media?parent=1100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/categories?post=1100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/tags?post=1100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}