{"id":736,"date":"2021-07-29T12:00:00","date_gmt":"2021-07-29T12:00:00","guid":{"rendered":"http:\/\/wec-new-site.local\/flexibilidad-regulatoria-y-cambios-tecnol-gicos-ponen-a-prue\/"},"modified":"2021-07-29T12:00:00","modified_gmt":"2021-07-29T12:00:00","slug":"flexibilidad-regulatoria-y-cambios-tecnol-gicos-ponen-a-prue","status":"publish","type":"post","link":"https:\/\/wec-chile.cl\/en\/flexibilidad-regulatoria-y-cambios-tecnol-gicos-ponen-a-prue\/","title":{"rendered":"Flexibilidad regulatoria y cambios tecnol\u00f3gicos ponen a prueba implementaci\u00f3n de sistemas de almacenamiento energ\u00e9tico"},"content":{"rendered":"<p>\u201cEl almacenamiento de energ\u00eda es una de las tecnolog\u00edas que nos va a permitir incorporar los vol\u00famenes de generaci\u00f3n el\u00e9ctrica a partir de fuentes renovables variables que ser\u00e1n necesarios para cumplir con la meta de carbono neutralidad a un m\u00ednimo costo\u201d. As\u00ed lo se\u00f1al\u00f3 Francisco Mu\u00f1oz, director de Estudios de Generadoras de Chile en el \u00faltimo conversatorio organizado por el cap\u00edtulo local del World Energy Council y en el que participaron representantes del sector energ\u00e9tico privado, la academia y el Estado.<\/p>\n<p>\u201cAlmacenamiento como driver de la descarbonizaci\u00f3n\u201d se denomin\u00f3 la cita en la que expusieron, aparte de Mu\u00f1oz, la directora de Asuntos Regulatorios de AES Andes, Paola Hartung; el coordinador del Centro de Energ\u00eda y Desarrollo Sustentable de la Universidad Diego Portales (UDP), Claudio Huepe; el jefe de la Unidad de Monitoreo y Regulaci\u00f3n de Mercado del ministerio de Energ\u00eda, Ricardo G\u00e1lvez, y Monserrat Garc\u00eda, profesional de la Divisi\u00f3n Energ\u00edas Sostenibles de la misma cartera y tambi\u00e9n Embajadora de Women in Energy.<\/p>\n<p>En el inicio, Huepe plante\u00f3 que la \u201cdescarbonizaci\u00f3n es solo una parte de la transici\u00f3n energ\u00e9tica, de tremenda complejidad. Es un comienzo importante y significativo, pero que nos deja un tremendo camino\u201d.<\/p>\n<p>\u201cEl almacenamiento juega un rol importante, pero dentro de un conjunto de acciones. La pregunta que necesitamos hacernos es qu\u00e9 tipo de regulaci\u00f3n, tanto para el almacenamiento como en general, requerimos para la transici\u00f3n energ\u00e9tica. De alguna manera, lo que estamos haciendo es insertando cambios en nuestra regulaci\u00f3n, pero que hasta cierto punto es una camisa de fuerza\u201d, advirti\u00f3 el acad\u00e9mico.<\/p>\n<p>En este contexto, Huepe llam\u00f3 a prestar atenci\u00f3n a los cambios vertiginosos que se est\u00e1n dando en tecnolog\u00eda, lo que podr\u00eda generar variaciones radicales en los costos.<\/p>\n<p>\u201cQuiz\u00e1s nos va a empezar a pasar que avanzamos en cambios normativos, como al reglamento de potencia que se viene discutiendo desde hace meses, pero que cuando se implementen ya estar\u00e1n ligeramente obsoletos. El almacenamiento deber\u00eda motivar una reflexi\u00f3n profunda de c\u00f3mo todo el sistema tendr\u00e1 que irse adaptando\u201d, recalc\u00f3.<\/p>\n<p>Ante esta inquietud, Ricardo Galvez, del ministerio de Energ\u00eda, estuvo de acuerdo en que se requiere flexibilidad regulatoria frente a los cambios tecnol\u00f3gicos, \u201cpero tambi\u00e9n se\u00f1ales claras de largo plazo a los inversionistas en este mercado de generaci\u00f3n que es intensivo\u201d.<\/p>\n<p>Descarbonizaci\u00f3n acelerada s\u00ed o s\u00ed.<\/p>\n<p>Complementando el debate, Paola Hartung, manifest\u00f3 \u201cque se requieren (art\u00edculos) transitorios razonables para que el mercado se pueda adaptar. Eso independiente de que detr\u00e1s hayan objetivos muy loables como lo es la descarbonizaci\u00f3n\u201d.<\/p>\n<p>\u201cLos cambios deben ser \u2018suaves\u2019, sobre todo ante inversiones recientes. Independiente de eso, yo creo que la descarbonizaci\u00f3n se va a dar en forma acelerada en paralelo a lo que pase con el reglamento de potencia. El cierre de centrales a carb\u00f3n ya se est\u00e1 dando y las empresas han tenido sus incentivos<\/p>","protected":false},"excerpt":{"rendered":"<p>\u201cAlmacenamiento como driver de la descarbonizaci\u00f3n\u201d se denomin\u00f3 la cita en la que expusieron Francisco Mu\u00f1oz, director de Estudios de Generadoras de Chile; la directora de Asuntos Regulatorios de&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-736","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts\/736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/comments?post=736"}],"version-history":[{"count":0,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts\/736\/revisions"}],"wp:attachment":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/media?parent=736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/categories?post=736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/tags?post=736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}