{"id":956,"date":"2019-10-08T12:00:00","date_gmt":"2019-10-08T12:00:00","guid":{"rendered":"http:\/\/wec-new-site.local\/ministro-de-energ-a-se-re-ne-con-principales-actores-del-sec\/"},"modified":"2019-10-08T12:00:00","modified_gmt":"2019-10-08T12:00:00","slug":"ministro-de-energ-a-se-re-ne-con-principales-actores-del-sec","status":"publish","type":"post","link":"https:\/\/wec-chile.cl\/en\/ministro-de-energ-a-se-re-ne-con-principales-actores-del-sec\/","title":{"rendered":"Ministro de Energ\u00eda se re\u00fane con principales actores del sector y aborda desaf\u00edos de la industria energ\u00e9tica"},"content":{"rendered":"<p>En la sexta versi\u00f3n del World Energy Caf\u00e9, patrocinado por Colb\u00fan, el ministro de Energ\u00eda, Juan Carlos Jobet, se reuni\u00f3 con socios del World Energy Council Chile (WEC) para compartir los principales ejes de trabajo e inquietudes de la cartera.<\/p>\n<p>Octubre, 2019. En un distendido y participativo di\u00e1logo, el Ministro de Energ\u00eda centr\u00f3 su presentaci\u00f3n en los desaf\u00edos de la cartera que lidera, adem\u00e1s de abordar los puntos clave que preocupan al sector, tales como el rol del ministerio frente a la COP25, la descarbonizaci\u00f3n de la matriz energ\u00e9tica, desarrollo del hidr\u00f3geno y asuntos ligados a la distribuci\u00f3n de la energ\u00eda en nuestro pa\u00eds.<\/p>\n<p>En este sentido, el ministro fue enf\u00e1tico en la necesidad de adaptarse a los cambios que se est\u00e1n generando en la industria, as\u00ed como los avances en tecnolog\u00eda y las transformaciones que experimenta la ciudadan\u00eda. Asimismo, recalc\u00f3 la importancia de que la comunidad entienda los beneficios directos que trae la transici\u00f3n hacia las energ\u00edas limpias, a trav\u00e9s de una correcta comunicaci\u00f3n desde el mundo energ\u00e9tico p\u00fablico-privado hacia la sociedad.<\/p>\n<p>\u201cLas compa\u00f1\u00edas est\u00e1n en el coraz\u00f3n de estos desaf\u00edos. A diferencia de otros, en este sector el ministerio ayuda a modificar las leyes, dicta reglamentos, est\u00e1 m\u00e1s en la normativa, pero la ejecuci\u00f3n concreta la hace el sector privado. Es por eso que tenemos que estar en di\u00e1logo constante con los privados\u201d, asever\u00f3 el presidente honorario de WEC Chile.<\/p>\n<p>Frente al tema de la COP25, Jobet asegur\u00f3 que si bien puede ser vista como una presi\u00f3n adicional frente a las contingencias medioambientales, el esfuerzo y compromiso del ministerio de Energ\u00eda \u201ces un trabajo que se est\u00e1 haciendo hace muchos a\u00f1os, la gente cree que esto es una revoluci\u00f3n que parti\u00f3 en los \u00faltimos 24 o 36 meses pero esto no es as\u00ed, esto parti\u00f3 hace mucho tiempo\u201d, asegur\u00f3.<\/p>\n<p>En cuanto a los principales objetivos en materia de regulaci\u00f3n, el mandatario revel\u00f3 que los ejes centrales se sit\u00faan en distribuci\u00f3n, flexibilidad, transmisi\u00f3n y quema de le\u00f1a. En cuanto a la distribuci\u00f3n de la electricidad, se\u00f1al\u00f3 que ser\u00e1 prioritario por ser el sector que lleva m\u00e1s a\u00f1os sin una reforma profunda. En segundo lugar, declar\u00f3 que la flexibilidad de la matriz energ\u00e9tica tambi\u00e9n es un eje importante, para que las renovables convivan con otras tecnolog\u00edas que permitan que la oferta y demanda se ajusten. En tercer lugar, se sit\u00faa el desaf\u00edo de la transmisi\u00f3n y por \u00faltimo, se presenta el desaf\u00edo de la quema de la le\u00f1a, problem\u00e1tica que a juicio del ministro, es la m\u00e1s grande actualmente en materia medioambiental.<\/p>\n<p>Javiera Aldunate, directora ejecutiva de WEC Chile, manifest\u00f3 que \u201cEstamos muy felices de contar con la participaci\u00f3n del ministro de Energ\u00eda, ya que es un sector que hoy experimenta una transformaci\u00f3n con la instalaci\u00f3n de energ\u00edas renovables. En este sentido, como plataforma de di\u00e1logo podemos sociabilizar el plan de carbono neutralidad, adem\u00e1s de relevar tem\u00e1ticas importantes mediante actividades de difusi\u00f3n y vinculaci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>En la sexta versi\u00f3n del World Energy Caf\u00e9, patrocinado por Colb\u00fan, el ministro de Energ\u00eda, Juan Carlos Jobet, se reuni\u00f3 con socios del World Energy Council Chile (WEC) para compartir los principales&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-956","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts\/956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/comments?post=956"}],"version-history":[{"count":0,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts\/956\/revisions"}],"wp:attachment":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/media?parent=956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/categories?post=956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/tags?post=956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}