{"id":964,"date":"2019-09-16T12:00:00","date_gmt":"2019-09-16T12:00:00","guid":{"rendered":"http:\/\/wec-new-site.local\/socio-del-mes-david-falc-n-deloitte\/"},"modified":"2019-09-16T12:00:00","modified_gmt":"2019-09-16T12:00:00","slug":"socio-del-mes-david-falc-n-deloitte","status":"publish","type":"post","link":"https:\/\/wec-chile.cl\/en\/socio-del-mes-david-falc-n-deloitte\/","title":{"rendered":"Socio del Mes | David Falc\u00f3n | DELOITTE"},"content":{"rendered":"<p>\u201cEn Deloitte nos hemos planteado liderar los procesos de transformaci\u00f3n energ\u00e9tica en el mundo y en Chile, por lo que estar asociados a organizaciones como WEC nos potencia como empresa proveedora de servicios\u201d.<\/p>\n<p>Para David Falc\u00f3n, Director de Risk Advisory en Deloitte, WEC Chile es \u201cuna de las m\u00e1s importantes tribunas de interacci\u00f3n en el pa\u00eds, que integra y promueve el desarrollo energ\u00e9tico en todas sus dimensiones. Adem\u00e1s, integra la red m\u00e1s relevante del pa\u00eds en l\u00edderes energ\u00e9ticos, la que est\u00e1 orientada a facilitar el di\u00e1logo nacional e internacional.\u00a0 Por \u00faltimo, es una plataforma para plantear desaf\u00edos p\u00fablico-privados en la que puedan converger ideas y proyectos, que ayuden al desarrollo sostenible de todo nuestro quehacer\u201d.<\/p>\n<p>En cuanto a los desaf\u00edos del sector en nuestro pa\u00eds, Falc\u00f3n declara que se centran en los avances en materia de descarbonizaci\u00f3n y en la irrupci\u00f3n de nuevas tecnolog\u00edas, tales como electromovilidad y almacenamiento.<\/p>\n<p>Por otra parte, en Deloitte reconocen la relevancia de WEC como plataforma de networking en el mundo de la energ\u00eda, y desde esa posici\u00f3n, ven \u201ccon buenos ojos reforzar ese liderazgo como empresa consultora para colaborar con nuestros clientes en el proceso de transformaci\u00f3n energ\u00e9tica que el pa\u00eds necesita\u201d asegur\u00f3 el Director de Risk Advisory.<\/p>\n<p>\u201cEn Deloitte, como l\u00edderes globales en consultor\u00eda, creemos que es muy relevante tener puntos de contacto y di\u00e1logo para los desaf\u00edos del mundo, del pa\u00eds y en particular del sector energ\u00e9tico. En este contexto, la empresa tiene una muy destacada experiencia en el rubro energ\u00e9tico, por lo que puede seguir contribuyendo al pa\u00eds, a las empresas y a la sociedad en este proceso de transformaci\u00f3n. Nos hemos planteado liderar los procesos de transformaci\u00f3n energ\u00e9tica en el mundo y en Chile, por lo que estar asociados a organizaciones como WEC nos potencia como empresa proveedora de Servicios\u201d asever\u00f3 Falc\u00f3n.<\/p>\n<p>A su vez, reforz\u00f3 que Deloitte puede ser un actor que facilite el di\u00e1logo debido a la cantidad de colaboradores distribuidos en diferentes funciones con un alto nivel de experiencia en el mundo energ\u00e9tico, adem\u00e1s de aportar de forma directa en los procesos de transformaci\u00f3n dentro de las empresas. Tambi\u00e9n, Falc\u00f3n enfatiz\u00f3 que Chile es un referente en adopci\u00f3n de energ\u00edas renovables, y a su vez se puede convertir en l\u00edder mundial en mitigaci\u00f3n y adaptaci\u00f3n al cambio clim\u00e1tico. \u201cComo Deloitte podemos apoyar a las empresas y al pa\u00eds en esta transformaci\u00f3n hacia una econom\u00eda m\u00e1s verde en t\u00e9rminos de emisiones de gases de efecto invernadero\u201d, confirm\u00f3.<\/p>\n<p>Para finalizar, el ejecutivo de Deloitte coment\u00f3 que \u201cMi expectativa es que WEC Chile siga avanzando hacia un liderazgo energ\u00e9tico en Chile y en la regi\u00f3n. En este contexto, es que esperemos que a trav\u00e9s de WEC se logre en Chile una mayor profundizaci\u00f3n en el proceso de transformaci\u00f3n energ\u00e9tico del pa\u00eds\u201d.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u201cEn Deloitte nos hemos planteado liderar los procesos de transformaci\u00f3n energ\u00e9tica en el mundo y en Chile, por lo que estar asociados a organizaciones como WEC nos potencia como empresa proveedora&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-964","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts\/964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/comments?post=964"}],"version-history":[{"count":0,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts\/964\/revisions"}],"wp:attachment":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/media?parent=964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/categories?post=964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/tags?post=964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}