{"id":988,"date":"2019-07-02T12:00:00","date_gmt":"2019-07-02T12:00:00","guid":{"rendered":"http:\/\/wec-new-site.local\/el-sistema-el-ctrico-est-preparado-ante-eclipse-solar\/"},"modified":"2019-07-02T12:00:00","modified_gmt":"2019-07-02T12:00:00","slug":"el-sistema-el-ctrico-est-preparado-ante-eclipse-solar","status":"publish","type":"post","link":"https:\/\/wec-chile.cl\/en\/el-sistema-el-ctrico-est-preparado-ante-eclipse-solar\/","title":{"rendered":"El sistema el\u00e9ctrico est\u00e1 preparado ante eclipse solar"},"content":{"rendered":"<p>Ministro de energ\u00eda: \u201cEl sistema est\u00e1 preparado para poder suplir la capacidad de generaci\u00f3n de la energ\u00eda solar, con centrales a gas e hidr\u00e1ulicas para asegurarle un suministro seguro igual que cualquier d\u00eda normal\u201d<\/p>\n<p>El ministro de Energ\u00eda, Juan Carlos Jobet, afirm\u00f3 que el Sistema El\u00e9ctrico Nacional est\u00e1 preparado para poder suplir la capacidad de generaci\u00f3n de alrededor de 1.500 MW de energ\u00eda solar que se perder\u00e1n a causa del eclipse que ocurrir\u00e1 este martes 2 de julio, pues se\u00f1al\u00f3 que la operaci\u00f3n del sistema se reemplazar\u00e1 con la generaci\u00f3n de gas natural e hidr\u00e1ulica proveniente de la zona centro sur del pa\u00eds.<\/p>\n<p>\u201cEl sistema est\u00e1 preparado para poder suplir la capacidad de generaci\u00f3n de la energ\u00eda solar, con centrales a gas e hidr\u00e1ulicas para asegurarle un suministro seguro igual que cualquier d\u00eda normal\u201d, sostuvo la autoridad.<\/p>\n<p>La autoridad visit\u00f3 el centro de operaciones del\u00a0Coordinador El\u00e9ctrico Nacional\u00a0para conocer las medidas que se realizar\u00e1n ma\u00f1ana para la operaci\u00f3n del sistema el\u00e9ctrico.<\/p>\n<p>El presidente del Consejo Directivo del organismo coordinador, Juan Carlos Olmedo, se\u00f1al\u00f3 que hace tres meses se comenz\u00f3 a trabajar para esta contingencia, \u201cpara desarrollar las estrategias operacionales que nos permitan pasar el d\u00eda de ma\u00f1ana sin problemas y con un suministro continuo, con la calidad adecuada\u201d.<\/p>\n<p>Seg\u00fan Olmedo, para la Regi\u00f3n de Coquimbo se espera un aumento de 30 MW en la demanda el\u00e9ctrica, debido a la mayor cantidad de personas que se encuentran en la zona para ver el fen\u00f3meno astron\u00f3mico, lo que equivale al 8% de la demanda de toda esa regi\u00f3n.<\/p>\n<p>\u201cPor otra parte, en la zona centro para la hora del eclipse, se prev\u00e9 una demanda aproximada de 2.800 MW, lo que representa una disminuci\u00f3n de 200 MW en el consumo\u201d, agreg\u00f3.<\/p>\n<p>Olmedo dijo que para este martes est\u00e1 programada la operaci\u00f3n de ocho centrales a gas, \u201clo que da un total de aproximadamente 2.400 MW que vamos a tener disponible\u201d.<\/p>\n<p>Medidas<br \/>\nDe acuerdo a lo informado por el Ministerio de Energ\u00eda, las principales actividades que el Coordinador est\u00e1 llevando a cabo para afrontar los efectos del eclipse en el Sistema El\u00e9ctrico Nacional son:<\/p>\n<p>Elaboraci\u00f3n de programas diarios de generaci\u00f3n para el d\u00eda 2 de julio, determinado flujos por las l\u00edneas de transmisi\u00f3n y reservas para el seguimiento de la demanda neta (demanda bruta \u2013 generaci\u00f3n renovable variable), considerando escenarios de hidrolog\u00eda h\u00fameda, media y seca, y considerando los casos con y sin puesta en servicio de las l\u00edneas de interconexi\u00f3n de 500 kV Pan de Az\u00facar \u2013 Polpaico.<br \/>\n \tElaboraci\u00f3n de pron\u00f3sticos de generaci\u00f3n renovable, en particular, de la reducci\u00f3n de generaci\u00f3n solar, a trav\u00e9s de empresa especialista en pron\u00f3sticos AWS TruePower, pron\u00f3sticos propios del Coordinador y de las empresas propietarias de parques solares. A medida que se acerque la fecha del evento se afinar\u00e1n los pron\u00f3sticos.<br \/>\n \tEjecuci\u00f3n de sesiones de capacitaci\u00f3n enfocadas en el eclipse para los ingenieros despachadores del centro de control del Coordina<\/p>","protected":false},"excerpt":{"rendered":"<p>Ministro de energ\u00eda: \u201cEl sistema est\u00e1 preparado para poder suplir la capacidad de generaci\u00f3n de la energ\u00eda solar, con centrales a gas e hidr\u00e1ulicas para asegurarle un suministro seguro igual que&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-988","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts\/988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/comments?post=988"}],"version-history":[{"count":0,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts\/988\/revisions"}],"wp:attachment":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/media?parent=988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/categories?post=988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/tags?post=988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}