{"id":991,"date":"2019-06-21T12:00:00","date_gmt":"2019-06-21T12:00:00","guid":{"rendered":"http:\/\/wec-new-site.local\/presidente-sebasti-n-pi-era-inaugura-carretera-el-ctrica-car\/"},"modified":"2019-06-21T12:00:00","modified_gmt":"2019-06-21T12:00:00","slug":"presidente-sebasti-n-pi-era-inaugura-carretera-el-ctrica-car","status":"publish","type":"post","link":"https:\/\/wec-chile.cl\/en\/presidente-sebasti-n-pi-era-inaugura-carretera-el-ctrica-car\/","title":{"rendered":"Presidente Sebasti\u00e1n Pi\u00f1era inaugura carretera el\u00e9ctrica Cardones-Polpaico"},"content":{"rendered":"<p>En la regi\u00f3n de Atacama, el presidente Sebasti\u00e1n Pi\u00f1era junto con el ministro de Energ\u00eda, Juan Carlos Jobet, y el ministro de Econom\u00eda, Juan Andr\u00e9s Fontaine, inauguraron la subestaci\u00f3n Nueva Cardones, la infraestructura de transporte el\u00e9ctrico m\u00e1s importante en m\u00e1s de\u00a030 a\u00f1os en Chile.<\/p>\n<p>Luego de m\u00e1s de un a\u00f1o de atraso, comenz\u00f3 la operaci\u00f3n de la carretera el\u00e9ctrica que une el sistema nacional con una extensi\u00f3n de 753 km. El proyecto cont\u00f3 con una inversi\u00f3n de US$1.000 millones y fortalecer\u00e1 la interconexi\u00f3n del Sistema El\u00e9ctrico Nacional, enlazando el Sistema El\u00e9ctrico del Norte Grande (SING) y el del centro-sur (SIC). En total, se trata de 1.728 torres desplegadas en 20 comunas de las regiones de Atacama, Coquimbo, Valpara\u00edso y Metropolitana. Con ello, el Sistema El\u00e9ctrico Nacional qued\u00f3 conectado a 500 kV.<\/p>\n<p>\u201cEsta l\u00ednea mejora la seguridad energ\u00e9tica porque viene a robustecer el sistema el\u00e9ctrico nacional. As\u00ed en a\u00f1os de sequ\u00eda o cat\u00e1strofes naturales, podremos responder en forma r\u00e1pida y trasladar energ\u00eda de un lugar a otro para asegurar el suministro. Es importante resaltar que esta carretera el\u00e9ctrica es clave para avanzar en la descarbonizaci\u00f3n de nuestra matriz\u201d, se\u00f1al\u00f3 el ministro de Energ\u00eda.<\/p>\n<p>En la pr\u00e1ctica, uno de los mayores beneficios de esta subestaci\u00f3n es que se abastecer\u00e1n aproximadamente 5,7 millones de hogares con electricidad de centrales de energ\u00edas renovables situadas en el norte del pa\u00eds, especialmente fotovoltaicas y e\u00f3licas. \u201cEs una muy buena noticia porque marca un importante hito para el sistema el\u00e9ctrico nacional, generando energ\u00eda cada vez m\u00e1s limpia y responsable con el medio ambiente. Adem\u00e1s de la importancia que aporta en la interconexi\u00f3n, se trata de un aporte ya que reemplaza generaci\u00f3n t\u00e9rmica por renovable\u201d, coment\u00f3 Javiera Aldunate, directora ejecutiva de WEC Chile.<\/p>","protected":false},"excerpt":{"rendered":"<p>En la regi\u00f3n de Atacama, el presidente Sebasti\u00e1n Pi\u00f1era junto con el ministro de Energ\u00eda, Juan Carlos Jobet, y el ministro de Econom\u00eda, Juan Andr\u00e9s Fontaine, inauguraron la subestaci\u00f3n Nueva&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-991","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts\/991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/comments?post=991"}],"version-history":[{"count":0,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/posts\/991\/revisions"}],"wp:attachment":[{"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/media?parent=991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/categories?post=991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wec-chile.cl\/en\/wp-json\/wp\/v2\/tags?post=991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}